{"id":66901,"date":"2026-06-16T10:16:01","date_gmt":"2026-06-16T08:16:01","guid":{"rendered":"https:\/\/coria.org\/ayuntamiento\/?p=66901"},"modified":"2026-06-17T08:09:30","modified_gmt":"2026-06-17T06:09:30","slug":"cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad","status":"publish","type":"post","link":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/","title":{"rendered":"Cauria Neuro presenta oficialmente los programas de normalizaci\u00f3n y deterioro cognitivo concedidos por el SEPAD"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Asociaci\u00f3n Cauria Neuro celebr\u00f3 recientemente, un acto institucional para la presentaci\u00f3n oficial de los programas de Normalizaci\u00f3n y de Atenci\u00f3n al Deterioro Cognitivo concedidos por el Servicio Extreme\u00f1o de Promoci\u00f3n de la Autonom\u00eda y Atenci\u00f3n a la Dependencia (SEPAD), con el objetivo de dar a conocer estas iniciativas, difundir su alcance y fortalecer la colaboraci\u00f3n entre las distintas administraciones y recursos sociales del territorio.<\/p>\n\n\n<figure class=\"wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026.webp\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" srcset=\"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026.webp 1920w, https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026-768x576.webp 768w, https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026-1536x1152.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n<p class=\"wp-block-paragraph\">El acto cont\u00f3 con la asistencia de representantes pol\u00edticos del Ayuntamiento de Coria, profesionales de los Servicios Sociales de Base y de la gerente territorial del Servicio Extreme\u00f1o de Promoci\u00f3n de la Autonom\u00eda y Atenci\u00f3n a la Dependencia (SEPAD) en la provincia de C\u00e1ceres, do\u00f1a Arancha S\u00e1nchez, en una jornada destinada a presentar oficialmente los programas concedidos a la entidad y a reforzar la coordinaci\u00f3n institucional en beneficio de las personas usuarias y sus familias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el encuentro, los asistentes tuvieron la oportunidad de conocer las instalaciones de Cauria Neuro y acercarse de primera mano al trabajo que la asociaci\u00f3n desarrolla en favor de las personas con discapacidad, en situaci\u00f3n de dependencia, con da\u00f1o cerebral adquirido, deterioro cognitivo y otras circunstancias derivadas de enfermedades o situaciones sobrevenidas que requieren apoyos especializados para favorecer su autonom\u00eda personal, inclusi\u00f3n social y calidad de vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se realiz\u00f3 una exposici\u00f3n detallada de los programas concedidos por el SEPAD, explicando sus objetivos, las actuaciones previstas y el perfil de las personas destinatarias. Estas iniciativas permitir\u00e1n seguir impulsando acciones orientadas a la promoci\u00f3n de la autonom\u00eda personal, la normalizaci\u00f3n, la estimulaci\u00f3n y rehabilitaci\u00f3n cognitiva, la participaci\u00f3n social y el acompa\u00f1amiento a las familias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada sirvi\u00f3 tambi\u00e9n para generar un espacio de encuentro entre profesionales e instituciones, favoreciendo el intercambio de experiencias, el conocimiento mutuo de los recursos existentes y la creaci\u00f3n de nuevas sinergias de trabajo que permitan ofrecer una atenci\u00f3n cada vez m\u00e1s coordinada y adaptada a las necesidades de la ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde Cauria Neuro se valor\u00f3 muy positivamente la celebraci\u00f3n de este acto institucional, destacando la importancia de continuar fortaleciendo la colaboraci\u00f3n con las administraciones p\u00fablicas y los recursos sociales de la comarca para seguir avanzando en la atenci\u00f3n especializada y la mejora de la calidad de vida de las personas con discapacidad, dependencia, da\u00f1o cerebral adquirido, deterioro cognitivo y sus familias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La asociaci\u00f3n agradece la presencia y el compromiso mostrado por el Ayuntamiento de Coria, los Servicios Sociales de Base y el SEPAD, reafirmando su voluntad de continuar trabajando de manera conjunta para promover una sociedad m\u00e1s inclusiva, accesible y comprometida con el bienestar de las personas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asociaci\u00f3n Cauria Neuro celebr\u00f3 recientemente, un acto institucional para la presentaci\u00f3n oficial de los programas de Normalizaci\u00f3n y de Atenci\u00f3n al Deterioro Cognitivo concedidos por el Servicio Extreme\u00f1o de Promoci\u00f3n de la Autonom\u00eda y Atenci\u00f3n a la Dependencia (SEPAD), con el objetivo de dar a conocer estas iniciativas, difundir su alcance y fortalecer la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":66902,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[9,2],"tags":[1162],"class_list":["post-66901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-noticias","tag-sepad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cauria Neuro presenta oficialmente los programas de normalizaci\u00f3n y deterioro cognitivo concedidos por el SEPAD - Ayuntamiento de Coria<\/title>\n<meta name=\"description\" content=\"La Asociaci\u00f3n Cauria Neuro celebr\u00f3 recientemente, un acto institucional para la presentaci\u00f3n oficial de los programas de Normalizaci\u00f3n y de Atenci\u00f3n al Deterioro Cognitivo concedidos por el Servicio Extreme\u00f1o de Promoci\u00f3n de la Autonom\u00eda y Atenci\u00f3n a la Dependencia (SEPAD), con el objetivo de dar a conocer estas iniciativas, difundir su alcance y fortalecer la colaboraci\u00f3n entre las distintas administraciones y recursos sociales del territorio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cauria Neuro presenta oficialmente los programas de normalizaci\u00f3n y deterioro cognitivo concedidos por el SEPAD\" \/>\n<meta property=\"og:description\" content=\"La Asociaci\u00f3n Cauria Neuro celebr\u00f3 recientemente, un acto institucional para la presentaci\u00f3n oficial de los programas de Normalizaci\u00f3n y de Atenci\u00f3n al Deterioro Cognitivo concedidos por el Servicio Extreme\u00f1o de Promoci\u00f3n de la Autonom\u00eda y Atenci\u00f3n a la Dependencia (SEPAD), con el objetivo de dar a conocer estas iniciativas, difundir su alcance y fortalecer la colaboraci\u00f3n entre las distintas administraciones y recursos sociales del territorio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Coria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ayuntamiento.de.Coria\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-16T08:16:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-17T06:09:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"ayuntamiento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Cauria Neuro presenta oficialmente los programas de normalizaci\u00f3n y deterioro cognitivo concedidos por el SEPAD\" \/>\n<meta name=\"twitter:description\" content=\"La Asociaci\u00f3n Cauria Neuro celebr\u00f3 recientemente, un acto institucional para la presentaci\u00f3n oficial de los programas de Normalizaci\u00f3n y de Atenci\u00f3n al Deterioro Cognitivo concedidos por el Servicio Extreme\u00f1o de Promoci\u00f3n de la Autonom\u00eda y Atenci\u00f3n a la Dependencia (SEPAD), con el objetivo de dar a conocer estas iniciativas, difundir su alcance y fortalecer la colaboraci\u00f3n entre las distintas administraciones y recursos sociales del territorio.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026.webp\" \/>\n<meta name=\"twitter:creator\" content=\"@Ayto_de_Coria\" \/>\n<meta name=\"twitter:site\" content=\"@Ayto_de_Coria\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ayuntamiento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/06\\\/16\\\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/06\\\/16\\\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\\\/\"},\"author\":{\"name\":\"ayuntamiento\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#\\\/schema\\\/person\\\/8bd589f0e13e8ae5aa06def7a599d622\"},\"headline\":\"Cauria Neuro presenta oficialmente los programas de normalizaci\u00f3n y deterioro cognitivo concedidos por el SEPAD\",\"datePublished\":\"2026-06-16T08:16:01+00:00\",\"dateModified\":\"2026-06-17T06:09:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/06\\\/16\\\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\\\/\"},\"wordCount\":481,\"publisher\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/06\\\/16\\\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/presentacion-sepad-2026.webp\",\"keywords\":[\"sepad\"],\"articleSection\":[\"Destacado\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/06\\\/16\\\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\\\/\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/06\\\/16\\\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\\\/\",\"name\":\"Cauria Neuro presenta oficialmente los programas de normalizaci\u00f3n y deterioro cognitivo concedidos por el SEPAD - Ayuntamiento de Coria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/06\\\/16\\\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/06\\\/16\\\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/presentacion-sepad-2026.webp\",\"datePublished\":\"2026-06-16T08:16:01+00:00\",\"dateModified\":\"2026-06-17T06:09:30+00:00\",\"description\":\"La Asociaci\u00f3n Cauria Neuro celebr\u00f3 recientemente, un acto institucional para la presentaci\u00f3n oficial de los programas de Normalizaci\u00f3n y de Atenci\u00f3n al Deterioro Cognitivo concedidos por el Servicio Extreme\u00f1o de Promoci\u00f3n de la Autonom\u00eda y Atenci\u00f3n a la Dependencia (SEPAD), con el objetivo de dar a conocer estas iniciativas, difundir su alcance y fortalecer la colaboraci\u00f3n entre las distintas administraciones y recursos sociales del territorio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/06\\\/16\\\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/06\\\/16\\\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/06\\\/16\\\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/presentacion-sepad-2026.webp\",\"contentUrl\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/presentacion-sepad-2026.webp\",\"width\":1920,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/06\\\/16\\\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cauria Neuro presenta oficialmente los programas de normalizaci\u00f3n y deterioro cognitivo concedidos por el SEPAD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#website\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/\",\"name\":\"Ayuntamiento de Coria\",\"description\":\"Web oficial del Ayuntamiento de Coria\",\"publisher\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#organization\"},\"alternateName\":\"Web Oficial del Ayuntamiento de Coria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#organization\",\"name\":\"Ayuntamiento de Coria\",\"alternateName\":\"Ayto de Coria\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/escudo-ayuntamiento-coria.png\",\"contentUrl\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/escudo-ayuntamiento-coria.png\",\"width\":511,\"height\":240,\"caption\":\"Ayuntamiento de Coria\"},\"image\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ayuntamiento.de.Coria\",\"https:\\\/\\\/x.com\\\/Ayto_de_Coria\",\"https:\\\/\\\/www.instagram.com\\\/coria.ayuntamiento\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AYUNTAMIENTOCORIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#\\\/schema\\\/person\\\/8bd589f0e13e8ae5aa06def7a599d622\",\"name\":\"ayuntamiento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/966e5ed73cad334adda5c87f49f2547f7082f7292c1b627cbb548744383b391c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/966e5ed73cad334adda5c87f49f2547f7082f7292c1b627cbb548744383b391c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/966e5ed73cad334adda5c87f49f2547f7082f7292c1b627cbb548744383b391c?s=96&d=mm&r=g\",\"caption\":\"ayuntamiento\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cauria Neuro presenta oficialmente los programas de normalizaci\u00f3n y deterioro cognitivo concedidos por el SEPAD - Ayuntamiento de Coria","description":"La Asociaci\u00f3n Cauria Neuro celebr\u00f3 recientemente, un acto institucional para la presentaci\u00f3n oficial de los programas de Normalizaci\u00f3n y de Atenci\u00f3n al Deterioro Cognitivo concedidos por el Servicio Extreme\u00f1o de Promoci\u00f3n de la Autonom\u00eda y Atenci\u00f3n a la Dependencia (SEPAD), con el objetivo de dar a conocer estas iniciativas, difundir su alcance y fortalecer la colaboraci\u00f3n entre las distintas administraciones y recursos sociales del territorio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/","og_locale":"es_ES","og_type":"article","og_title":"Cauria Neuro presenta oficialmente los programas de normalizaci\u00f3n y deterioro cognitivo concedidos por el SEPAD","og_description":"La Asociaci\u00f3n Cauria Neuro celebr\u00f3 recientemente, un acto institucional para la presentaci\u00f3n oficial de los programas de Normalizaci\u00f3n y de Atenci\u00f3n al Deterioro Cognitivo concedidos por el Servicio Extreme\u00f1o de Promoci\u00f3n de la Autonom\u00eda y Atenci\u00f3n a la Dependencia (SEPAD), con el objetivo de dar a conocer estas iniciativas, difundir su alcance y fortalecer la colaboraci\u00f3n entre las distintas administraciones y recursos sociales del territorio.","og_url":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/","og_site_name":"Ayuntamiento de Coria","article_publisher":"https:\/\/www.facebook.com\/Ayuntamiento.de.Coria","article_published_time":"2026-06-16T08:16:01+00:00","article_modified_time":"2026-06-17T06:09:30+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026.webp","type":"image\/webp"}],"author":"ayuntamiento","twitter_card":"summary_large_image","twitter_title":"Cauria Neuro presenta oficialmente los programas de normalizaci\u00f3n y deterioro cognitivo concedidos por el SEPAD","twitter_description":"La Asociaci\u00f3n Cauria Neuro celebr\u00f3 recientemente, un acto institucional para la presentaci\u00f3n oficial de los programas de Normalizaci\u00f3n y de Atenci\u00f3n al Deterioro Cognitivo concedidos por el Servicio Extreme\u00f1o de Promoci\u00f3n de la Autonom\u00eda y Atenci\u00f3n a la Dependencia (SEPAD), con el objetivo de dar a conocer estas iniciativas, difundir su alcance y fortalecer la colaboraci\u00f3n entre las distintas administraciones y recursos sociales del territorio.","twitter_image":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026.webp","twitter_creator":"@Ayto_de_Coria","twitter_site":"@Ayto_de_Coria","twitter_misc":{"Escrito por":"ayuntamiento","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/#article","isPartOf":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/"},"author":{"name":"ayuntamiento","@id":"https:\/\/coria.org\/ayuntamiento\/#\/schema\/person\/8bd589f0e13e8ae5aa06def7a599d622"},"headline":"Cauria Neuro presenta oficialmente los programas de normalizaci\u00f3n y deterioro cognitivo concedidos por el SEPAD","datePublished":"2026-06-16T08:16:01+00:00","dateModified":"2026-06-17T06:09:30+00:00","mainEntityOfPage":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/"},"wordCount":481,"publisher":{"@id":"https:\/\/coria.org\/ayuntamiento\/#organization"},"image":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/#primaryimage"},"thumbnailUrl":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026.webp","keywords":["sepad"],"articleSection":["Destacado","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/","url":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/","name":"Cauria Neuro presenta oficialmente los programas de normalizaci\u00f3n y deterioro cognitivo concedidos por el SEPAD - Ayuntamiento de Coria","isPartOf":{"@id":"https:\/\/coria.org\/ayuntamiento\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/#primaryimage"},"image":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/#primaryimage"},"thumbnailUrl":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026.webp","datePublished":"2026-06-16T08:16:01+00:00","dateModified":"2026-06-17T06:09:30+00:00","description":"La Asociaci\u00f3n Cauria Neuro celebr\u00f3 recientemente, un acto institucional para la presentaci\u00f3n oficial de los programas de Normalizaci\u00f3n y de Atenci\u00f3n al Deterioro Cognitivo concedidos por el Servicio Extreme\u00f1o de Promoci\u00f3n de la Autonom\u00eda y Atenci\u00f3n a la Dependencia (SEPAD), con el objetivo de dar a conocer estas iniciativas, difundir su alcance y fortalecer la colaboraci\u00f3n entre las distintas administraciones y recursos sociales del territorio.","breadcrumb":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/#primaryimage","url":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026.webp","contentUrl":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026.webp","width":1920,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/06\/16\/cauria-neuro-presenta-oficialmente-los-programas-de-normalizacion-y-deterioro-cognitivo-concedidos-por-el-sepad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/coria.org\/ayuntamiento\/"},{"@type":"ListItem","position":2,"name":"Cauria Neuro presenta oficialmente los programas de normalizaci\u00f3n y deterioro cognitivo concedidos por el SEPAD"}]},{"@type":"WebSite","@id":"https:\/\/coria.org\/ayuntamiento\/#website","url":"https:\/\/coria.org\/ayuntamiento\/","name":"Ayuntamiento de Coria","description":"Web oficial del Ayuntamiento de Coria","publisher":{"@id":"https:\/\/coria.org\/ayuntamiento\/#organization"},"alternateName":"Web Oficial del Ayuntamiento de Coria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coria.org\/ayuntamiento\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/coria.org\/ayuntamiento\/#organization","name":"Ayuntamiento de Coria","alternateName":"Ayto de Coria","url":"https:\/\/coria.org\/ayuntamiento\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coria.org\/ayuntamiento\/#\/schema\/logo\/image\/","url":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2020\/12\/escudo-ayuntamiento-coria.png","contentUrl":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2020\/12\/escudo-ayuntamiento-coria.png","width":511,"height":240,"caption":"Ayuntamiento de Coria"},"image":{"@id":"https:\/\/coria.org\/ayuntamiento\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ayuntamiento.de.Coria","https:\/\/x.com\/Ayto_de_Coria","https:\/\/www.instagram.com\/coria.ayuntamiento\/","https:\/\/www.youtube.com\/user\/AYUNTAMIENTOCORIA"]},{"@type":"Person","@id":"https:\/\/coria.org\/ayuntamiento\/#\/schema\/person\/8bd589f0e13e8ae5aa06def7a599d622","name":"ayuntamiento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/966e5ed73cad334adda5c87f49f2547f7082f7292c1b627cbb548744383b391c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/966e5ed73cad334adda5c87f49f2547f7082f7292c1b627cbb548744383b391c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/966e5ed73cad334adda5c87f49f2547f7082f7292c1b627cbb548744383b391c?s=96&d=mm&r=g","caption":"ayuntamiento"}}]}},"uagb_featured_image_src":{"full":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026.webp",1920,1440,false],"thumbnail":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026-150x150.webp",150,150,true],"medium":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026.webp",1920,1440,false],"medium_large":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026-768x576.webp",768,576,true],"large":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026.webp",1920,1440,false],"thumblist":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026-300x300.webp",300,300,true],"thumbrelated":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026-500x500.webp",500,500,true],"meccarouselthumb":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026-474x324.webp",474,324,true],"gridsquare":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026-391x260.webp",391,260,true],"tileview":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026-300x400.webp",300,400,true],"1536x1536":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026-1536x1152.webp",1536,1152,true],"2048x2048":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/06\/presentacion-sepad-2026.webp",1920,1440,false]},"uagb_author_info":{"display_name":"ayuntamiento","author_link":"https:\/\/coria.org\/ayuntamiento\/index.php\/author\/ayuntamiento\/"},"uagb_comment_info":0,"uagb_excerpt":"La Asociaci\u00f3n Cauria Neuro celebr\u00f3 recientemente, un acto institucional para la presentaci\u00f3n oficial de los programas de Normalizaci\u00f3n y de Atenci\u00f3n al Deterioro Cognitivo concedidos por el Servicio Extreme\u00f1o de Promoci\u00f3n de la Autonom\u00eda y Atenci\u00f3n a la Dependencia (SEPAD), con el objetivo de dar a conocer estas iniciativas, difundir su alcance y fortalecer la&hellip;","_links":{"self":[{"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/posts\/66901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/comments?post=66901"}],"version-history":[{"count":1,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/posts\/66901\/revisions"}],"predecessor-version":[{"id":66903,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/posts\/66901\/revisions\/66903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/media\/66902"}],"wp:attachment":[{"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/media?parent=66901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/categories?post=66901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/tags?post=66901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}