{"id":66590,"date":"2026-05-06T13:23:35","date_gmt":"2026-05-06T11:23:35","guid":{"rendered":"https:\/\/coria.org\/ayuntamiento\/?p=66590"},"modified":"2026-05-06T13:24:04","modified_gmt":"2026-05-06T11:24:04","slug":"el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso","status":"publish","type":"post","link":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/","title":{"rendered":"El Ayuntamiento inicia las obras de reforma del acerado en la carretera de Montehermoso"},"content":{"rendered":"\n<p>El Ayuntamiento de Coria ha iniciado este mi\u00e9rcoles las obras de reforma del acerado en la carretera de Montehermoso, unos trabajos que se incluyen en el proyecto \u201cPavimentaciones y asfaltados en la ciudad de Coria en 3 lotes\u201d, en concreto el Lote 1: Reforma de acerados municipales.<\/p>\n\n\n<figure class=\"wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1343\" src=\"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26.webp\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" srcset=\"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26.webp 1920w, https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26-768x537.webp 768w, https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26-1536x1074.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n<p>Estas actuaciones tienen como objetivo la mejora y renovaci\u00f3n de la acera en esta v\u00eda, una zona transitada por peatones, reforzando la seguridad y accesibilidad para todos los vecinos.<\/p>\n\n\n\n<p>Cabe recordar que dentro de este mismo proyecto ya se han llevado a cabo actuaciones en otras calles como Cadenetas y, recientemente en la traves\u00eda Alfonso VII, y se continuar\u00e1 progresivamente en diferentes puntos de la ciudad.<\/p>\n\n\n\n<p>Cabe recordar que, el contrato fue adjudicado a la empresa Ambienta Ingenier\u00eda y Servicios Agrarios y Forestales, S.L.U., por un importe de 85.985 euros (m\u00e1s IVA), y est\u00e1 siendo ejecutado con remanentes del Ayuntamiento.<\/p>\n\n\n\n<p>Estas obras contemplan no solo la renovaci\u00f3n del acerado, sino tambi\u00e9n actuaciones accesorias como pintura y mejoras en accesibilidad, contribuyendo a una mayor seguridad para los peatones y a la modernizaci\u00f3n de las infraestructuras urbanas.<\/p>\n\n\n\n<p>Con esta iniciativa, el Ayuntamiento de Coria contin\u00faa avanzando en su compromiso con el mantenimiento y mejora del entorno urbano, atendiendo a las necesidades de los vecinos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Coria ha iniciado este mi\u00e9rcoles las obras de reforma del acerado en la carretera de Montehermoso, unos trabajos que se incluyen en el proyecto \u201cPavimentaciones y asfaltados en la ciudad de Coria en 3 lotes\u201d, en concreto el Lote 1: Reforma de acerados municipales. Estas actuaciones tienen como objetivo la mejora y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":66591,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[9,2],"tags":[883],"class_list":["post-66590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-noticias","tag-obras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Ayuntamiento inicia las obras de reforma del acerado en la carretera de Montehermoso - Ayuntamiento de Coria<\/title>\n<meta name=\"description\" content=\"El Ayuntamiento de Coria ha iniciado este mi\u00e9rcoles las obras de reforma del acerado en la carretera de Montehermoso, unos trabajos que se incluyen en el proyecto \u201cPavimentaciones y asfaltados en la ciudad de Coria en 3 lotes\u201d, en concreto el Lote 1: Reforma de acerados municipales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Ayuntamiento inicia las obras de reforma del acerado en la carretera de Montehermoso\" \/>\n<meta property=\"og:description\" content=\"El Ayuntamiento de Coria ha iniciado este mi\u00e9rcoles las obras de reforma del acerado en la carretera de Montehermoso, unos trabajos que se incluyen en el proyecto \u201cPavimentaciones y asfaltados en la ciudad de Coria en 3 lotes\u201d, en concreto el Lote 1: Reforma de acerados municipales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Coria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ayuntamiento.de.Coria\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-06T11:23:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T11:24:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1343\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"ayuntamiento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"El Ayuntamiento inicia las obras de reforma del acerado en la carretera de Montehermoso\" \/>\n<meta name=\"twitter:description\" content=\"El Ayuntamiento de Coria ha iniciado este mi\u00e9rcoles las obras de reforma del acerado en la carretera de Montehermoso, unos trabajos que se incluyen en el proyecto \u201cPavimentaciones y asfaltados en la ciudad de Coria en 3 lotes\u201d, en concreto el Lote 1: Reforma de acerados municipales.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26.webp\" \/>\n<meta name=\"twitter:creator\" content=\"@Ayto_de_Coria\" \/>\n<meta name=\"twitter:site\" content=\"@Ayto_de_Coria\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ayuntamiento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/05\\\/06\\\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/05\\\/06\\\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\\\/\"},\"author\":{\"name\":\"ayuntamiento\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#\\\/schema\\\/person\\\/8bd589f0e13e8ae5aa06def7a599d622\"},\"headline\":\"El Ayuntamiento inicia las obras de reforma del acerado en la carretera de Montehermoso\",\"datePublished\":\"2026-05-06T11:23:35+00:00\",\"dateModified\":\"2026-05-06T11:24:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/05\\\/06\\\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\\\/\"},\"wordCount\":232,\"publisher\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/05\\\/06\\\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/obras-acerado-26.webp\",\"keywords\":[\"obras\"],\"articleSection\":[\"Destacado\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/05\\\/06\\\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\\\/\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/05\\\/06\\\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\\\/\",\"name\":\"El Ayuntamiento inicia las obras de reforma del acerado en la carretera de Montehermoso - Ayuntamiento de Coria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/05\\\/06\\\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/05\\\/06\\\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/obras-acerado-26.webp\",\"datePublished\":\"2026-05-06T11:23:35+00:00\",\"dateModified\":\"2026-05-06T11:24:04+00:00\",\"description\":\"El Ayuntamiento de Coria ha iniciado este mi\u00e9rcoles las obras de reforma del acerado en la carretera de Montehermoso, unos trabajos que se incluyen en el proyecto \u201cPavimentaciones y asfaltados en la ciudad de Coria en 3 lotes\u201d, en concreto el Lote 1: Reforma de acerados municipales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/05\\\/06\\\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/05\\\/06\\\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/05\\\/06\\\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/obras-acerado-26.webp\",\"contentUrl\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/obras-acerado-26.webp\",\"width\":1920,\"height\":1343},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/05\\\/06\\\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ayuntamiento inicia las obras de reforma del acerado en la carretera de Montehermoso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#website\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/\",\"name\":\"Ayuntamiento de Coria\",\"description\":\"Web oficial del Ayuntamiento de Coria\",\"publisher\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#organization\"},\"alternateName\":\"Web Oficial del Ayuntamiento de Coria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#organization\",\"name\":\"Ayuntamiento de Coria\",\"alternateName\":\"Ayto de Coria\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/escudo-ayuntamiento-coria.png\",\"contentUrl\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/escudo-ayuntamiento-coria.png\",\"width\":511,\"height\":240,\"caption\":\"Ayuntamiento de Coria\"},\"image\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ayuntamiento.de.Coria\",\"https:\\\/\\\/x.com\\\/Ayto_de_Coria\",\"https:\\\/\\\/www.instagram.com\\\/coria.ayuntamiento\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AYUNTAMIENTOCORIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#\\\/schema\\\/person\\\/8bd589f0e13e8ae5aa06def7a599d622\",\"name\":\"ayuntamiento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/966e5ed73cad334adda5c87f49f2547f7082f7292c1b627cbb548744383b391c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/966e5ed73cad334adda5c87f49f2547f7082f7292c1b627cbb548744383b391c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/966e5ed73cad334adda5c87f49f2547f7082f7292c1b627cbb548744383b391c?s=96&d=mm&r=g\",\"caption\":\"ayuntamiento\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ayuntamiento inicia las obras de reforma del acerado en la carretera de Montehermoso - Ayuntamiento de Coria","description":"El Ayuntamiento de Coria ha iniciado este mi\u00e9rcoles las obras de reforma del acerado en la carretera de Montehermoso, unos trabajos que se incluyen en el proyecto \u201cPavimentaciones y asfaltados en la ciudad de Coria en 3 lotes\u201d, en concreto el Lote 1: Reforma de acerados municipales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/","og_locale":"es_ES","og_type":"article","og_title":"El Ayuntamiento inicia las obras de reforma del acerado en la carretera de Montehermoso","og_description":"El Ayuntamiento de Coria ha iniciado este mi\u00e9rcoles las obras de reforma del acerado en la carretera de Montehermoso, unos trabajos que se incluyen en el proyecto \u201cPavimentaciones y asfaltados en la ciudad de Coria en 3 lotes\u201d, en concreto el Lote 1: Reforma de acerados municipales.","og_url":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/","og_site_name":"Ayuntamiento de Coria","article_publisher":"https:\/\/www.facebook.com\/Ayuntamiento.de.Coria","article_published_time":"2026-05-06T11:23:35+00:00","article_modified_time":"2026-05-06T11:24:04+00:00","og_image":[{"width":1920,"height":1343,"url":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26.webp","type":"image\/webp"}],"author":"ayuntamiento","twitter_card":"summary_large_image","twitter_title":"El Ayuntamiento inicia las obras de reforma del acerado en la carretera de Montehermoso","twitter_description":"El Ayuntamiento de Coria ha iniciado este mi\u00e9rcoles las obras de reforma del acerado en la carretera de Montehermoso, unos trabajos que se incluyen en el proyecto \u201cPavimentaciones y asfaltados en la ciudad de Coria en 3 lotes\u201d, en concreto el Lote 1: Reforma de acerados municipales.","twitter_image":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26.webp","twitter_creator":"@Ayto_de_Coria","twitter_site":"@Ayto_de_Coria","twitter_misc":{"Escrito por":"ayuntamiento","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/#article","isPartOf":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/"},"author":{"name":"ayuntamiento","@id":"https:\/\/coria.org\/ayuntamiento\/#\/schema\/person\/8bd589f0e13e8ae5aa06def7a599d622"},"headline":"El Ayuntamiento inicia las obras de reforma del acerado en la carretera de Montehermoso","datePublished":"2026-05-06T11:23:35+00:00","dateModified":"2026-05-06T11:24:04+00:00","mainEntityOfPage":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/"},"wordCount":232,"publisher":{"@id":"https:\/\/coria.org\/ayuntamiento\/#organization"},"image":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/#primaryimage"},"thumbnailUrl":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26.webp","keywords":["obras"],"articleSection":["Destacado","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/","url":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/","name":"El Ayuntamiento inicia las obras de reforma del acerado en la carretera de Montehermoso - Ayuntamiento de Coria","isPartOf":{"@id":"https:\/\/coria.org\/ayuntamiento\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/#primaryimage"},"image":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/#primaryimage"},"thumbnailUrl":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26.webp","datePublished":"2026-05-06T11:23:35+00:00","dateModified":"2026-05-06T11:24:04+00:00","description":"El Ayuntamiento de Coria ha iniciado este mi\u00e9rcoles las obras de reforma del acerado en la carretera de Montehermoso, unos trabajos que se incluyen en el proyecto \u201cPavimentaciones y asfaltados en la ciudad de Coria en 3 lotes\u201d, en concreto el Lote 1: Reforma de acerados municipales.","breadcrumb":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/#primaryimage","url":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26.webp","contentUrl":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26.webp","width":1920,"height":1343},{"@type":"BreadcrumbList","@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/05\/06\/el-ayuntamiento-inicia-las-obras-de-reforma-del-acerado-en-la-carretera-de-montehermoso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/coria.org\/ayuntamiento\/"},{"@type":"ListItem","position":2,"name":"El Ayuntamiento inicia las obras de reforma del acerado en la carretera de Montehermoso"}]},{"@type":"WebSite","@id":"https:\/\/coria.org\/ayuntamiento\/#website","url":"https:\/\/coria.org\/ayuntamiento\/","name":"Ayuntamiento de Coria","description":"Web oficial del Ayuntamiento de Coria","publisher":{"@id":"https:\/\/coria.org\/ayuntamiento\/#organization"},"alternateName":"Web Oficial del Ayuntamiento de Coria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coria.org\/ayuntamiento\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/coria.org\/ayuntamiento\/#organization","name":"Ayuntamiento de Coria","alternateName":"Ayto de Coria","url":"https:\/\/coria.org\/ayuntamiento\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coria.org\/ayuntamiento\/#\/schema\/logo\/image\/","url":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2020\/12\/escudo-ayuntamiento-coria.png","contentUrl":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2020\/12\/escudo-ayuntamiento-coria.png","width":511,"height":240,"caption":"Ayuntamiento de Coria"},"image":{"@id":"https:\/\/coria.org\/ayuntamiento\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ayuntamiento.de.Coria","https:\/\/x.com\/Ayto_de_Coria","https:\/\/www.instagram.com\/coria.ayuntamiento\/","https:\/\/www.youtube.com\/user\/AYUNTAMIENTOCORIA"]},{"@type":"Person","@id":"https:\/\/coria.org\/ayuntamiento\/#\/schema\/person\/8bd589f0e13e8ae5aa06def7a599d622","name":"ayuntamiento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/966e5ed73cad334adda5c87f49f2547f7082f7292c1b627cbb548744383b391c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/966e5ed73cad334adda5c87f49f2547f7082f7292c1b627cbb548744383b391c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/966e5ed73cad334adda5c87f49f2547f7082f7292c1b627cbb548744383b391c?s=96&d=mm&r=g","caption":"ayuntamiento"}}]}},"uagb_featured_image_src":{"full":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26.webp",1920,1343,false],"thumbnail":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26-150x150.webp",150,150,true],"medium":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26.webp",1920,1343,false],"medium_large":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26-768x537.webp",768,537,true],"large":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26.webp",1920,1343,false],"thumblist":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26-300x300.webp",300,300,true],"thumbrelated":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26-500x500.webp",500,500,true],"meccarouselthumb":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26-474x324.webp",474,324,true],"gridsquare":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26-391x260.webp",391,260,true],"tileview":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26-300x400.webp",300,400,true],"1536x1536":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26-1536x1074.webp",1536,1074,true],"2048x2048":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/05\/obras-acerado-26.webp",1920,1343,false]},"uagb_author_info":{"display_name":"ayuntamiento","author_link":"https:\/\/coria.org\/ayuntamiento\/index.php\/author\/ayuntamiento\/"},"uagb_comment_info":0,"uagb_excerpt":"El Ayuntamiento de Coria ha iniciado este mi\u00e9rcoles las obras de reforma del acerado en la carretera de Montehermoso, unos trabajos que se incluyen en el proyecto \u201cPavimentaciones y asfaltados en la ciudad de Coria en 3 lotes\u201d, en concreto el Lote 1: Reforma de acerados municipales. Estas actuaciones tienen como objetivo la mejora y&hellip;","_links":{"self":[{"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/posts\/66590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/comments?post=66590"}],"version-history":[{"count":1,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/posts\/66590\/revisions"}],"predecessor-version":[{"id":66592,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/posts\/66590\/revisions\/66592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/media\/66591"}],"wp:attachment":[{"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/media?parent=66590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/categories?post=66590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/tags?post=66590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}