{"id":66444,"date":"2026-04-17T08:19:44","date_gmt":"2026-04-17T06:19:44","guid":{"rendered":"https:\/\/coria.org\/ayuntamiento\/?p=66444"},"modified":"2026-04-17T08:20:11","modified_gmt":"2026-04-17T06:20:11","slug":"coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo","status":"publish","type":"post","link":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/","title":{"rendered":"Coria licita la renovaci\u00f3n de las pistas de p\u00e1del del Polideportivo Municipal \u201cLa Isla\u201d tras los da\u00f1os causados por la borrasca Leonardo"},"content":{"rendered":"\n<p>El Ayuntamiento de Coria ha sacado a licitaci\u00f3n el contrato para el suministro e instalaci\u00f3n de c\u00e9sped artificial fibrilado en las cuatro pistas de p\u00e1del del polideportivo municipal, con un presupuesto base de 26.571,60 euros.<\/p>\n\n\n<figure class=\"wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel.webp\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" srcset=\"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel.webp 1600w, https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel-768x576.webp 768w, https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel-1536x1152.webp 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n<p>La alcaldesa de Coria ha firmado en la ma\u00f1ana de hoy el inicio de este expediente, con el objetivo de agilizar los tr\u00e1mites administrativos y comenzar las obras lo antes posible. Esta actuaci\u00f3n responde a la necesidad de reparar los da\u00f1os ocasionados por la borrasca Leonardo y la crecida del r\u00edo del pasado mes de febrero, que afectaron de manera significativa a estas instalaciones deportivas.<\/p>\n\n\n\n<p>En palabras de la alcaldesa, Almudena Domingo, \u201cdesde el primer momento tuvimos claro que \u00edbamos a actuar con rapidez para recuperar unas instalaciones muy utilizadas por nuestros vecinos. Esta licitaci\u00f3n es una muestra del compromiso de este equipo de gobierno con el deporte y con la mejora de los servicios p\u00fablicos municipales, adem\u00e1s de ofrecer unas condiciones \u00f3ptimas para la pr\u00e1ctica del p\u00e1del, un deporte con gran arraigo en Coria\u201d.<\/p>\n\n\n\n<p>Cabe destacar que, tal y como se\u00f1alaba recientemente un aficionado local, las pistas de p\u00e1del de Coria fueron de las primeras de car\u00e1cter municipal en construirse en la zona, siendo adem\u00e1s la ciudad pionera en la organizaci\u00f3n de campeonatos de esta disciplina deportiva.<\/p>\n\n\n\n<p>En este sentido, la alcaldesa ha a\u00f1adido que \u201cCoria ha sido hist\u00f3ricamente un referente en este deporte, y queremos seguir si\u00e9ndolo, apoyando tanto a los aficionados como a las actividades deportivas que dinamizan nuestra ciudad\u201d.<\/p>\n\n\n\n<p>El plazo de presentaci\u00f3n de ofertas permanecer\u00e1 abierto hasta el pr\u00f3ximo 23 de abril de 2026. Toda la documentaci\u00f3n relativa a esta licitaci\u00f3n se encuentra disponible en la sede electr\u00f3nica del Ayuntamiento de Coria, dentro del Perfil del Contratante.<\/p>\n\n\n\n<p>\u201cSeguimos trabajando para que Coria cuente con instalaciones deportivas de calidad, accesibles y seguras, porque invertir en deporte es tambi\u00e9n invertir en salud, convivencia y calidad de vida\u201d, ha concluido.<\/p>\n\n\n\n<p>Desde el Ayuntamiento de Coria se contin\u00faa apostando por la mejora y mantenimiento de las infraestructuras deportivas municipales, fomentando as\u00ed la pr\u00e1ctica del deporte y el bienestar de la ciudadan\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Coria ha sacado a licitaci\u00f3n el contrato para el suministro e instalaci\u00f3n de c\u00e9sped artificial fibrilado en las cuatro pistas de p\u00e1del del polideportivo municipal, con un presupuesto base de 26.571,60 euros. La alcaldesa de Coria ha firmado en la ma\u00f1ana de hoy el inicio de este expediente, con el objetivo de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":66445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[9,2],"tags":[403,915],"class_list":["post-66444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-noticias","tag-deporte","tag-padel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coria licita la renovaci\u00f3n de las pistas de p\u00e1del del Polideportivo Municipal \u201cLa Isla\u201d tras los da\u00f1os causados por la borrasca Leonardo - Ayuntamiento de Coria<\/title>\n<meta name=\"description\" content=\"El Ayuntamiento de Coria ha sacado a licitaci\u00f3n el contrato para el suministro e instalaci\u00f3n de c\u00e9sped artificial fibrilado en las cuatro pistas de p\u00e1del del polideportivo municipal, con un presupuesto base de 26.571,60 euros.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coria licita la renovaci\u00f3n de las pistas de p\u00e1del del Polideportivo Municipal \u201cLa Isla\u201d tras los da\u00f1os causados por la borrasca Leonardo\" \/>\n<meta property=\"og:description\" content=\"El Ayuntamiento de Coria ha sacado a licitaci\u00f3n el contrato para el suministro e instalaci\u00f3n de c\u00e9sped artificial fibrilado en las cuatro pistas de p\u00e1del del polideportivo municipal, con un presupuesto base de 26.571,60 euros.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Coria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ayuntamiento.de.Coria\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T06:19:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T06:20:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"prensa@coria.org\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coria licita la renovaci\u00f3n de las pistas de p\u00e1del del Polideportivo Municipal \u201cLa Isla\u201d tras los da\u00f1os causados por la borrasca Leonardo\" \/>\n<meta name=\"twitter:description\" content=\"El Ayuntamiento de Coria ha sacado a licitaci\u00f3n el contrato para el suministro e instalaci\u00f3n de c\u00e9sped artificial fibrilado en las cuatro pistas de p\u00e1del del polideportivo municipal, con un presupuesto base de 26.571,60 euros.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel.webp\" \/>\n<meta name=\"twitter:creator\" content=\"@Ayto_de_Coria\" \/>\n<meta name=\"twitter:site\" content=\"@Ayto_de_Coria\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"prensa@coria.org\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/04\\\/17\\\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/04\\\/17\\\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\\\/\"},\"author\":{\"name\":\"prensa@coria.org\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#\\\/schema\\\/person\\\/e599808bcace6131357c531f55c6b600\"},\"headline\":\"Coria licita la renovaci\u00f3n de las pistas de p\u00e1del del Polideportivo Municipal \u201cLa Isla\u201d tras los da\u00f1os causados por la borrasca Leonardo\",\"datePublished\":\"2026-04-17T06:19:44+00:00\",\"dateModified\":\"2026-04-17T06:20:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/04\\\/17\\\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\\\/\"},\"wordCount\":400,\"publisher\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/04\\\/17\\\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/pista-padel.webp\",\"keywords\":[\"deporte\",\"padel\"],\"articleSection\":[\"Destacado\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/04\\\/17\\\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\\\/\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/04\\\/17\\\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\\\/\",\"name\":\"Coria licita la renovaci\u00f3n de las pistas de p\u00e1del del Polideportivo Municipal \u201cLa Isla\u201d tras los da\u00f1os causados por la borrasca Leonardo - Ayuntamiento de Coria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/04\\\/17\\\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/04\\\/17\\\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/pista-padel.webp\",\"datePublished\":\"2026-04-17T06:19:44+00:00\",\"dateModified\":\"2026-04-17T06:20:11+00:00\",\"description\":\"El Ayuntamiento de Coria ha sacado a licitaci\u00f3n el contrato para el suministro e instalaci\u00f3n de c\u00e9sped artificial fibrilado en las cuatro pistas de p\u00e1del del polideportivo municipal, con un presupuesto base de 26.571,60 euros.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/04\\\/17\\\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/04\\\/17\\\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/04\\\/17\\\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/pista-padel.webp\",\"contentUrl\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/pista-padel.webp\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/index.php\\\/2026\\\/04\\\/17\\\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coria licita la renovaci\u00f3n de las pistas de p\u00e1del del Polideportivo Municipal \u201cLa Isla\u201d tras los da\u00f1os causados por la borrasca Leonardo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#website\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/\",\"name\":\"Ayuntamiento de Coria\",\"description\":\"Web oficial del Ayuntamiento de Coria\",\"publisher\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#organization\"},\"alternateName\":\"Web Oficial del Ayuntamiento de Coria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#organization\",\"name\":\"Ayuntamiento de Coria\",\"alternateName\":\"Ayto de Coria\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/escudo-ayuntamiento-coria.png\",\"contentUrl\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/escudo-ayuntamiento-coria.png\",\"width\":511,\"height\":240,\"caption\":\"Ayuntamiento de Coria\"},\"image\":{\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ayuntamiento.de.Coria\",\"https:\\\/\\\/x.com\\\/Ayto_de_Coria\",\"https:\\\/\\\/www.instagram.com\\\/coria.ayuntamiento\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AYUNTAMIENTOCORIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/coria.org\\\/ayuntamiento\\\/#\\\/schema\\\/person\\\/e599808bcace6131357c531f55c6b600\",\"name\":\"prensa@coria.org\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/27aedb317acfc6f08831cc400fc47b05e64be7cc19749d7a736bdf9b11b9fc8b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/27aedb317acfc6f08831cc400fc47b05e64be7cc19749d7a736bdf9b11b9fc8b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/27aedb317acfc6f08831cc400fc47b05e64be7cc19749d7a736bdf9b11b9fc8b?s=96&d=mm&r=g\",\"caption\":\"prensa@coria.org\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coria licita la renovaci\u00f3n de las pistas de p\u00e1del del Polideportivo Municipal \u201cLa Isla\u201d tras los da\u00f1os causados por la borrasca Leonardo - Ayuntamiento de Coria","description":"El Ayuntamiento de Coria ha sacado a licitaci\u00f3n el contrato para el suministro e instalaci\u00f3n de c\u00e9sped artificial fibrilado en las cuatro pistas de p\u00e1del del polideportivo municipal, con un presupuesto base de 26.571,60 euros.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/","og_locale":"es_ES","og_type":"article","og_title":"Coria licita la renovaci\u00f3n de las pistas de p\u00e1del del Polideportivo Municipal \u201cLa Isla\u201d tras los da\u00f1os causados por la borrasca Leonardo","og_description":"El Ayuntamiento de Coria ha sacado a licitaci\u00f3n el contrato para el suministro e instalaci\u00f3n de c\u00e9sped artificial fibrilado en las cuatro pistas de p\u00e1del del polideportivo municipal, con un presupuesto base de 26.571,60 euros.","og_url":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/","og_site_name":"Ayuntamiento de Coria","article_publisher":"https:\/\/www.facebook.com\/Ayuntamiento.de.Coria","article_published_time":"2026-04-17T06:19:44+00:00","article_modified_time":"2026-04-17T06:20:11+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel.webp","type":"image\/webp"}],"author":"prensa@coria.org","twitter_card":"summary_large_image","twitter_title":"Coria licita la renovaci\u00f3n de las pistas de p\u00e1del del Polideportivo Municipal \u201cLa Isla\u201d tras los da\u00f1os causados por la borrasca Leonardo","twitter_description":"El Ayuntamiento de Coria ha sacado a licitaci\u00f3n el contrato para el suministro e instalaci\u00f3n de c\u00e9sped artificial fibrilado en las cuatro pistas de p\u00e1del del polideportivo municipal, con un presupuesto base de 26.571,60 euros.","twitter_image":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel.webp","twitter_creator":"@Ayto_de_Coria","twitter_site":"@Ayto_de_Coria","twitter_misc":{"Escrito por":"prensa@coria.org","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/#article","isPartOf":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/"},"author":{"name":"prensa@coria.org","@id":"https:\/\/coria.org\/ayuntamiento\/#\/schema\/person\/e599808bcace6131357c531f55c6b600"},"headline":"Coria licita la renovaci\u00f3n de las pistas de p\u00e1del del Polideportivo Municipal \u201cLa Isla\u201d tras los da\u00f1os causados por la borrasca Leonardo","datePublished":"2026-04-17T06:19:44+00:00","dateModified":"2026-04-17T06:20:11+00:00","mainEntityOfPage":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/"},"wordCount":400,"publisher":{"@id":"https:\/\/coria.org\/ayuntamiento\/#organization"},"image":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/#primaryimage"},"thumbnailUrl":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel.webp","keywords":["deporte","padel"],"articleSection":["Destacado","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/","url":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/","name":"Coria licita la renovaci\u00f3n de las pistas de p\u00e1del del Polideportivo Municipal \u201cLa Isla\u201d tras los da\u00f1os causados por la borrasca Leonardo - Ayuntamiento de Coria","isPartOf":{"@id":"https:\/\/coria.org\/ayuntamiento\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/#primaryimage"},"image":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/#primaryimage"},"thumbnailUrl":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel.webp","datePublished":"2026-04-17T06:19:44+00:00","dateModified":"2026-04-17T06:20:11+00:00","description":"El Ayuntamiento de Coria ha sacado a licitaci\u00f3n el contrato para el suministro e instalaci\u00f3n de c\u00e9sped artificial fibrilado en las cuatro pistas de p\u00e1del del polideportivo municipal, con un presupuesto base de 26.571,60 euros.","breadcrumb":{"@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/#primaryimage","url":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel.webp","contentUrl":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel.webp","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/coria.org\/ayuntamiento\/index.php\/2026\/04\/17\/coria-licita-la-renovacion-de-las-pistas-de-padel-del-polideportivo-municipal-la-isla-tras-los-danos-causados-por-la-borrasca-leonardo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/coria.org\/ayuntamiento\/"},{"@type":"ListItem","position":2,"name":"Coria licita la renovaci\u00f3n de las pistas de p\u00e1del del Polideportivo Municipal \u201cLa Isla\u201d tras los da\u00f1os causados por la borrasca Leonardo"}]},{"@type":"WebSite","@id":"https:\/\/coria.org\/ayuntamiento\/#website","url":"https:\/\/coria.org\/ayuntamiento\/","name":"Ayuntamiento de Coria","description":"Web oficial del Ayuntamiento de Coria","publisher":{"@id":"https:\/\/coria.org\/ayuntamiento\/#organization"},"alternateName":"Web Oficial del Ayuntamiento de Coria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coria.org\/ayuntamiento\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/coria.org\/ayuntamiento\/#organization","name":"Ayuntamiento de Coria","alternateName":"Ayto de Coria","url":"https:\/\/coria.org\/ayuntamiento\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coria.org\/ayuntamiento\/#\/schema\/logo\/image\/","url":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2020\/12\/escudo-ayuntamiento-coria.png","contentUrl":"https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2020\/12\/escudo-ayuntamiento-coria.png","width":511,"height":240,"caption":"Ayuntamiento de Coria"},"image":{"@id":"https:\/\/coria.org\/ayuntamiento\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ayuntamiento.de.Coria","https:\/\/x.com\/Ayto_de_Coria","https:\/\/www.instagram.com\/coria.ayuntamiento\/","https:\/\/www.youtube.com\/user\/AYUNTAMIENTOCORIA"]},{"@type":"Person","@id":"https:\/\/coria.org\/ayuntamiento\/#\/schema\/person\/e599808bcace6131357c531f55c6b600","name":"prensa@coria.org","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/27aedb317acfc6f08831cc400fc47b05e64be7cc19749d7a736bdf9b11b9fc8b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/27aedb317acfc6f08831cc400fc47b05e64be7cc19749d7a736bdf9b11b9fc8b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/27aedb317acfc6f08831cc400fc47b05e64be7cc19749d7a736bdf9b11b9fc8b?s=96&d=mm&r=g","caption":"prensa@coria.org"}}]}},"uagb_featured_image_src":{"full":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel.webp",1600,1200,false],"thumbnail":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel-150x150.webp",150,150,true],"medium":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel.webp",1600,1200,false],"medium_large":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel-768x576.webp",768,576,true],"large":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel.webp",1600,1200,false],"thumblist":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel-300x300.webp",300,300,true],"thumbrelated":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel-500x500.webp",500,500,true],"meccarouselthumb":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel-474x324.webp",474,324,true],"gridsquare":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel-391x260.webp",391,260,true],"tileview":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel-300x400.webp",300,400,true],"1536x1536":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel-1536x1152.webp",1536,1152,true],"2048x2048":["https:\/\/coria.org\/ayuntamiento\/wp-content\/uploads\/2026\/04\/pista-padel.webp",1600,1200,false]},"uagb_author_info":{"display_name":"prensa@coria.org","author_link":"https:\/\/coria.org\/ayuntamiento\/index.php\/author\/prensacoria-org\/"},"uagb_comment_info":0,"uagb_excerpt":"El Ayuntamiento de Coria ha sacado a licitaci\u00f3n el contrato para el suministro e instalaci\u00f3n de c\u00e9sped artificial fibrilado en las cuatro pistas de p\u00e1del del polideportivo municipal, con un presupuesto base de 26.571,60 euros. La alcaldesa de Coria ha firmado en la ma\u00f1ana de hoy el inicio de este expediente, con el objetivo de&hellip;","_links":{"self":[{"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/posts\/66444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/comments?post=66444"}],"version-history":[{"count":1,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/posts\/66444\/revisions"}],"predecessor-version":[{"id":66446,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/posts\/66444\/revisions\/66446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/media\/66445"}],"wp:attachment":[{"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/media?parent=66444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/categories?post=66444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coria.org\/ayuntamiento\/index.php\/wp-json\/wp\/v2\/tags?post=66444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}